{"id":358,"date":"2021-08-26T21:16:57","date_gmt":"2021-08-26T19:16:57","guid":{"rendered":"https:\/\/wanderblog.kirsch-heike.de\/?p=358"},"modified":"2021-08-26T21:16:57","modified_gmt":"2021-08-26T19:16:57","slug":"schweiz-tag-17","status":"publish","type":"post","link":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/2021\/08\/26\/schweiz-tag-17\/","title":{"rendered":"Schweiz Tag 17"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211217-768x1024.jpg\" alt=\"\" class=\"wp-image-359\" srcset=\"https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211217-768x1024.jpg 768w, https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211217-225x300.jpg 225w, https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211217-1152x1536.jpg 1152w, https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211217-1200x1601.jpg 1200w, https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211217.jpg 1360w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211323-768x1024.jpg\" alt=\"\" class=\"wp-image-360\" srcset=\"https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211323-768x1024.jpg 768w, https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211323-225x300.jpg 225w, https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211323-1152x1536.jpg 1152w, https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211323-1200x1600.jpg 1200w, https:\/\/wanderblog.kirsch-heike.de\/wp-content\/uploads\/2021\/08\/20210826_211323.jpg 1244w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Die Aussicht beim Betten machen ist schon beeindruckend. Und zum Abend habe ich dann noch aus all den Tomaten die aufgrund des Hagels letzte Woche nicht mehr gut aushalten einen riesengro\u00dfen Topf Tomatensauce oder wie man hier sagt, Sugo, gemacht. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Aussicht beim Betten machen ist schon beeindruckend. Und zum Abend habe ich dann noch aus all den Tomaten die aufgrund des Hagels letzte Woche nicht mehr gut aushalten einen riesengro\u00dfen Topf Tomatensauce oder wie man hier sagt, Sugo, gemacht.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-358","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/wp-json\/wp\/v2\/posts\/358"}],"collection":[{"href":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/wp-json\/wp\/v2\/comments?post=358"}],"version-history":[{"count":1,"href":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/wp-json\/wp\/v2\/posts\/358\/revisions"}],"predecessor-version":[{"id":361,"href":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/wp-json\/wp\/v2\/posts\/358\/revisions\/361"}],"wp:attachment":[{"href":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/wp-json\/wp\/v2\/media?parent=358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/wp-json\/wp\/v2\/categories?post=358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wanderblog.kirsch-heike.de\/index.php\/wp-json\/wp\/v2\/tags?post=358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}